{"id":695,"date":"2021-05-24T11:54:02","date_gmt":"2021-05-24T09:54:02","guid":{"rendered":"http:\/\/knjiznice.nsk.hr\/obrovac\/?p=695"},"modified":"2021-05-24T11:54:09","modified_gmt":"2021-05-24T09:54:09","slug":"hai-radionica","status":"publish","type":"post","link":"https:\/\/knjiznice.nsk.hr\/obrovac\/2021\/05\/24\/hai-radionica\/","title":{"rendered":"HAI radionica"},"content":{"rendered":"<div dir=\"auto\">U sklopu Godine \u010ditanja ugostili smo g\u0111u. Tanju Tandaru iz udruge \u201epoVUcizakulturu\u201c koja nam je predstavila igra\u010dke inspirirane hrvatskom kulturnom ba\u0161tinom. Zvutka, Znati\u017eeljna nit, Pagus i \u010ci\u010dolin samo se neke od igara koje su pred\u0161kolci Dje\u010djeg vrti\u0107a Obrovac stvorili i koje su ih uvele u svijet ba\u0161tine.<\/div>\n<div dir=\"auto\"><img loading=\"lazy\" class=\"alignnone size-medium wp-image-696\" src=\"http:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/189666559_283460360165188_5111372121819968589_n-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/189666559_283460360165188_5111372121819968589_n-300x200.jpg 300w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/189666559_283460360165188_5111372121819968589_n-1024x683.jpg 1024w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/189666559_283460360165188_5111372121819968589_n-768x512.jpg 768w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/189666559_283460360165188_5111372121819968589_n-600x400.jpg 600w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/189666559_283460360165188_5111372121819968589_n-1536x1025.jpg 1536w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/189666559_283460360165188_5111372121819968589_n.jpg 1686w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" class=\"alignnone size-medium wp-image-697\" src=\"http:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188285504_283460233498534_5646399396773154055_n-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188285504_283460233498534_5646399396773154055_n-300x200.jpg 300w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188285504_283460233498534_5646399396773154055_n-1024x683.jpg 1024w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188285504_283460233498534_5646399396773154055_n-768x512.jpg 768w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188285504_283460233498534_5646399396773154055_n-600x400.jpg 600w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188285504_283460233498534_5646399396773154055_n-1536x1025.jpg 1536w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188285504_283460233498534_5646399396773154055_n.jpg 1686w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" class=\"alignnone size-medium wp-image-698\" src=\"http:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188492327_283460176831873_1745215274841198933_n-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188492327_283460176831873_1745215274841198933_n-300x200.jpg 300w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188492327_283460176831873_1745215274841198933_n-1024x683.jpg 1024w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188492327_283460176831873_1745215274841198933_n-768x512.jpg 768w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188492327_283460176831873_1745215274841198933_n-600x400.jpg 600w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188492327_283460176831873_1745215274841198933_n-1536x1025.jpg 1536w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188492327_283460176831873_1745215274841198933_n.jpg 1686w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" class=\"alignnone size-medium wp-image-699\" src=\"http:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/189779361_283460143498543_986107961277423765_n-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/189779361_283460143498543_986107961277423765_n-300x200.jpg 300w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/189779361_283460143498543_986107961277423765_n-1024x683.jpg 1024w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/189779361_283460143498543_986107961277423765_n-768x512.jpg 768w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/189779361_283460143498543_986107961277423765_n-600x400.jpg 600w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/189779361_283460143498543_986107961277423765_n-1536x1025.jpg 1536w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/189779361_283460143498543_986107961277423765_n.jpg 1686w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" class=\"alignnone size-medium wp-image-700\" src=\"http:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188356588_283459810165243_3886555338170690805_n-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188356588_283459810165243_3886555338170690805_n-300x200.jpg 300w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188356588_283459810165243_3886555338170690805_n-1024x683.jpg 1024w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188356588_283459810165243_3886555338170690805_n-768x512.jpg 768w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188356588_283459810165243_3886555338170690805_n-600x400.jpg 600w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188356588_283459810165243_3886555338170690805_n-1536x1025.jpg 1536w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188356588_283459810165243_3886555338170690805_n.jpg 1686w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" class=\"alignnone size-medium wp-image-701\" src=\"http:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188815827_283459756831915_5612640460852386404_n-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188815827_283459756831915_5612640460852386404_n-300x200.jpg 300w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188815827_283459756831915_5612640460852386404_n-1024x683.jpg 1024w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188815827_283459756831915_5612640460852386404_n-768x512.jpg 768w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188815827_283459756831915_5612640460852386404_n-600x400.jpg 600w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188815827_283459756831915_5612640460852386404_n-1536x1025.jpg 1536w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188815827_283459756831915_5612640460852386404_n.jpg 1686w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" class=\"alignnone size-medium wp-image-702\" src=\"http:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188912119_283459713498586_2001439245737390826_n-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188912119_283459713498586_2001439245737390826_n-300x200.jpg 300w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188912119_283459713498586_2001439245737390826_n-1024x683.jpg 1024w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188912119_283459713498586_2001439245737390826_n-768x512.jpg 768w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188912119_283459713498586_2001439245737390826_n-600x400.jpg 600w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188912119_283459713498586_2001439245737390826_n-1536x1025.jpg 1536w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188912119_283459713498586_2001439245737390826_n.jpg 1686w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" class=\"alignnone size-medium wp-image-704\" src=\"http:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188509234_283459626831928_8076175408308275253_n-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188509234_283459626831928_8076175408308275253_n-300x200.jpg 300w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188509234_283459626831928_8076175408308275253_n-1024x683.jpg 1024w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188509234_283459626831928_8076175408308275253_n-768x512.jpg 768w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188509234_283459626831928_8076175408308275253_n-600x400.jpg 600w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188509234_283459626831928_8076175408308275253_n-1536x1025.jpg 1536w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188509234_283459626831928_8076175408308275253_n.jpg 1686w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" class=\"alignnone size-medium wp-image-705\" src=\"http:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188482557_283459580165266_924957799037034950_n-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188482557_283459580165266_924957799037034950_n-300x200.jpg 300w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188482557_283459580165266_924957799037034950_n-1024x683.jpg 1024w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188482557_283459580165266_924957799037034950_n-768x512.jpg 768w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188482557_283459580165266_924957799037034950_n-600x400.jpg 600w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188482557_283459580165266_924957799037034950_n-1536x1025.jpg 1536w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188482557_283459580165266_924957799037034950_n.jpg 1686w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" class=\"alignnone size-medium wp-image-706\" src=\"http:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/189038788_283459523498605_7776527599959971113_n-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/189038788_283459523498605_7776527599959971113_n-300x200.jpg 300w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/189038788_283459523498605_7776527599959971113_n-1024x683.jpg 1024w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/189038788_283459523498605_7776527599959971113_n-768x512.jpg 768w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/189038788_283459523498605_7776527599959971113_n-600x400.jpg 600w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/189038788_283459523498605_7776527599959971113_n-1536x1025.jpg 1536w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/189038788_283459523498605_7776527599959971113_n.jpg 1686w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" class=\"alignnone size-medium wp-image-707\" src=\"http:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188108614_283459396831951_8603721614947102134_n-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188108614_283459396831951_8603721614947102134_n-300x200.jpg 300w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188108614_283459396831951_8603721614947102134_n-1024x683.jpg 1024w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188108614_283459396831951_8603721614947102134_n-768x512.jpg 768w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188108614_283459396831951_8603721614947102134_n-600x400.jpg 600w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188108614_283459396831951_8603721614947102134_n-1536x1025.jpg 1536w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/188108614_283459396831951_8603721614947102134_n.jpg 1686w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" class=\"alignnone size-medium wp-image-708\" src=\"http:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/189462000_283459196831971_4497716103377076834_n-223x300.jpg\" alt=\"\" width=\"223\" height=\"300\" srcset=\"https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/189462000_283459196831971_4497716103377076834_n-223x300.jpg 223w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/189462000_283459196831971_4497716103377076834_n-762x1024.jpg 762w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/189462000_283459196831971_4497716103377076834_n-768x1032.jpg 768w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/189462000_283459196831971_4497716103377076834_n-600x806.jpg 600w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/189462000_283459196831971_4497716103377076834_n-1143x1536.jpg 1143w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/189462000_283459196831971_4497716103377076834_n.jpg 1488w\" sizes=\"(max-width: 223px) 100vw, 223px\" \/> <img loading=\"lazy\" class=\"alignnone size-medium wp-image-709\" src=\"http:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/189018670_283460320165192_2724595190454227297_n-199x300.jpg\" alt=\"\" width=\"199\" height=\"300\" srcset=\"https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/189018670_283460320165192_2724595190454227297_n-199x300.jpg 199w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/189018670_283460320165192_2724595190454227297_n-680x1024.jpg 680w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/189018670_283460320165192_2724595190454227297_n-768x1156.jpg 768w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/189018670_283460320165192_2724595190454227297_n-600x903.jpg 600w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/189018670_283460320165192_2724595190454227297_n-1020x1536.jpg 1020w, https:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/189018670_283460320165192_2724595190454227297_n.jpg 1120w\" sizes=\"(max-width: 199px) 100vw, 199px\" \/><\/div>\n","protected":false},"excerpt":{"rendered":"<p>U sklopu Godine \u010ditanja ugostili smo g\u0111u. Tanju Tandaru iz udruge \u201epoVUcizakulturu\u201c koja nam je predstavila igra\u010dke inspirirane hrvatskom kulturnom ba\u0161tinom. Zvutka, Znati\u017eeljna nit, Pagus i \u010ci\u010dolin samo se neke od igara koje su pred\u0161kolci Dje\u010djeg vrti\u0107a Obrovac stvorili i koje su ih uvele u svijet ba\u0161tine.<\/p>\n","protected":false},"author":165,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[4],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/knjiznice.nsk.hr\/obrovac\/2021\/05\/24\/hai-radionica\/\" \/>\n<meta property=\"og:locale\" content=\"hr_HR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HAI radionica - Pu\u010dko otvoreno u\u010dili\u0161te-Knji\u017enica i \u010ditaonica Obrovac\" \/>\n<meta property=\"og:description\" content=\"U sklopu Godine \u010ditanja ugostili smo g\u0111u. Tanju Tandaru iz udruge \u201epoVUcizakulturu\u201c koja nam je predstavila igra\u010dke inspirirane hrvatskom kulturnom ba\u0161tinom. Zvutka, Znati\u017eeljna nit, Pagus i \u010ci\u010dolin samo se neke od igara koje su pred\u0161kolci Dje\u010djeg vrti\u0107a Obrovac stvorili i koje su ih uvele u svijet ba\u0161tine.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/knjiznice.nsk.hr\/obrovac\/2021\/05\/24\/hai-radionica\/\" \/>\n<meta property=\"og:site_name\" content=\"Pu\u010dko otvoreno u\u010dili\u0161te-Knji\u017enica i \u010ditaonica Obrovac\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-24T09:54:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-24T09:54:09+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/189666559_283460360165188_5111372121819968589_n-300x200.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Procijenjeno vrijeme \u010ditanja\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/knjiznice.nsk.hr\/obrovac\/#website\",\"url\":\"http:\/\/knjiznice.nsk.hr\/obrovac\/\",\"name\":\"Pu\\u010dko otvoreno u\\u010dili\\u0161te-Knji\\u017enica i \\u010ditaonica Obrovac\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"http:\/\/knjiznice.nsk.hr\/obrovac\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"hr\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/knjiznice.nsk.hr\/obrovac\/2021\/05\/24\/hai-radionica\/#primaryimage\",\"inLanguage\":\"hr\",\"url\":\"http:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/189666559_283460360165188_5111372121819968589_n-300x200.jpg\",\"contentUrl\":\"http:\/\/knjiznice.nsk.hr\/obrovac\/wp-content\/uploads\/sites\/101\/2021\/05\/189666559_283460360165188_5111372121819968589_n-300x200.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/knjiznice.nsk.hr\/obrovac\/2021\/05\/24\/hai-radionica\/#webpage\",\"url\":\"https:\/\/knjiznice.nsk.hr\/obrovac\/2021\/05\/24\/hai-radionica\/\",\"name\":\"HAI radionica - Pu\\u010dko otvoreno u\\u010dili\\u0161te-Knji\\u017enica i \\u010ditaonica Obrovac\",\"isPartOf\":{\"@id\":\"http:\/\/knjiznice.nsk.hr\/obrovac\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/knjiznice.nsk.hr\/obrovac\/2021\/05\/24\/hai-radionica\/#primaryimage\"},\"datePublished\":\"2021-05-24T09:54:02+00:00\",\"dateModified\":\"2021-05-24T09:54:09+00:00\",\"author\":{\"@id\":\"http:\/\/knjiznice.nsk.hr\/obrovac\/#\/schema\/person\/28ed387f817d8132e000a337eaae89a2\"},\"breadcrumb\":{\"@id\":\"https:\/\/knjiznice.nsk.hr\/obrovac\/2021\/05\/24\/hai-radionica\/#breadcrumb\"},\"inLanguage\":\"hr\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/knjiznice.nsk.hr\/obrovac\/2021\/05\/24\/hai-radionica\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/knjiznice.nsk.hr\/obrovac\/2021\/05\/24\/hai-radionica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"http:\/\/knjiznice.nsk.hr\/obrovac\/\",\"url\":\"http:\/\/knjiznice.nsk.hr\/obrovac\/\",\"name\":\"Po\\u010detna stranica\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@id\":\"https:\/\/knjiznice.nsk.hr\/obrovac\/2021\/05\/24\/hai-radionica\/#webpage\"}}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/knjiznice.nsk.hr\/obrovac\/#\/schema\/person\/28ed387f817d8132e000a337eaae89a2\",\"name\":\"obrovac\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/knjiznice.nsk.hr\/obrovac\/#personlogo\",\"inLanguage\":\"hr\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/281be2e7e7f272a89209ef9863d01f75?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/281be2e7e7f272a89209ef9863d01f75?s=96&d=mm&r=g\",\"caption\":\"obrovac\"},\"url\":\"https:\/\/knjiznice.nsk.hr\/obrovac\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/knjiznice.nsk.hr\/obrovac\/wp-json\/wp\/v2\/posts\/695"}],"collection":[{"href":"https:\/\/knjiznice.nsk.hr\/obrovac\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/knjiznice.nsk.hr\/obrovac\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/knjiznice.nsk.hr\/obrovac\/wp-json\/wp\/v2\/users\/165"}],"replies":[{"embeddable":true,"href":"https:\/\/knjiznice.nsk.hr\/obrovac\/wp-json\/wp\/v2\/comments?post=695"}],"version-history":[{"count":1,"href":"https:\/\/knjiznice.nsk.hr\/obrovac\/wp-json\/wp\/v2\/posts\/695\/revisions"}],"predecessor-version":[{"id":710,"href":"https:\/\/knjiznice.nsk.hr\/obrovac\/wp-json\/wp\/v2\/posts\/695\/revisions\/710"}],"wp:attachment":[{"href":"https:\/\/knjiznice.nsk.hr\/obrovac\/wp-json\/wp\/v2\/media?parent=695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/knjiznice.nsk.hr\/obrovac\/wp-json\/wp\/v2\/categories?post=695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/knjiznice.nsk.hr\/obrovac\/wp-json\/wp\/v2\/tags?post=695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}