{"id":14,"count":3,"description":"","link":"https:\/\/knjiznice.nsk.hr\/babina-greda\/category\/razno\/","name":"Razno","slug":"razno","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Arhiva Razno &ndash; Op\u0107inska narodna knji\u017enica Babina Greda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/knjiznice.nsk.hr\/babina-greda\/category\/razno\/\" \/>\n<meta property=\"og:locale\" content=\"hr_HR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arhiva Razno &ndash; Op\u0107inska narodna knji\u017enica Babina Greda\" \/>\n<meta property=\"og:url\" content=\"https:\/\/knjiznice.nsk.hr\/babina-greda\/category\/razno\/\" \/>\n<meta property=\"og:site_name\" content=\"Op\u0107inska narodna knji\u017enica Babina Greda\" \/>\n<meta property=\"og:image\" content=\"https:\/\/knjiznice.nsk.hr\/babina-greda\/wp-content\/uploads\/sites\/72\/2016\/01\/IMG_20150904_080152.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2982\" \/>\n\t<meta property=\"og:image:height\" content=\"1678\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/knjiznice.nsk.hr\/babina-greda\/#organization\",\"name\":\"Op\\u0107inska narodna knji\\u017enica Babina Greda\",\"url\":\"https:\/\/knjiznice.nsk.hr\/babina-greda\/\",\"sameAs\":[\"https:\/\/web.facebook.com\/opcinska.narodna.knjiznica.babina.greda\/?ref=bookmarks\",\"https:\/\/www.instagram.com\/narodnaknjiznica_bg\/\",\"https:\/\/www.youtube.com\/channel\/UC4GLISM7P4Kh8XCIuNsLjHA?view_as=subscriber\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/knjiznice.nsk.hr\/babina-greda\/#logo\",\"inLanguage\":\"hr\",\"url\":\"http:\/\/knjiznice.nsk.hr\/babina-greda\/wp-content\/uploads\/sites\/72\/2017\/05\/logo.jpg\",\"contentUrl\":\"http:\/\/knjiznice.nsk.hr\/babina-greda\/wp-content\/uploads\/sites\/72\/2017\/05\/logo.jpg\",\"width\":1056,\"height\":1368,\"caption\":\"Op\\u0107inska narodna knji\\u017enica Babina Greda\"},\"image\":{\"@id\":\"https:\/\/knjiznice.nsk.hr\/babina-greda\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/knjiznice.nsk.hr\/babina-greda\/#website\",\"url\":\"https:\/\/knjiznice.nsk.hr\/babina-greda\/\",\"name\":\"Op\\u0107inska narodna knji\\u017enica Babina Greda\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/knjiznice.nsk.hr\/babina-greda\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/knjiznice.nsk.hr\/babina-greda\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"hr\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/knjiznice.nsk.hr\/babina-greda\/category\/razno\/#webpage\",\"url\":\"https:\/\/knjiznice.nsk.hr\/babina-greda\/category\/razno\/\",\"name\":\"Arhiva Razno &ndash; Op\\u0107inska narodna knji\\u017enica Babina Greda\",\"isPartOf\":{\"@id\":\"https:\/\/knjiznice.nsk.hr\/babina-greda\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/knjiznice.nsk.hr\/babina-greda\/category\/razno\/#breadcrumb\"},\"inLanguage\":\"hr\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/knjiznice.nsk.hr\/babina-greda\/category\/razno\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/knjiznice.nsk.hr\/babina-greda\/category\/razno\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/knjiznice.nsk.hr\/babina-greda\/\",\"url\":\"https:\/\/knjiznice.nsk.hr\/babina-greda\/\",\"name\":\"Po\\u010detna stranica\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@id\":\"https:\/\/knjiznice.nsk.hr\/babina-greda\/category\/razno\/#webpage\"}}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/knjiznice.nsk.hr\/babina-greda\/wp-json\/wp\/v2\/categories\/14"}],"collection":[{"href":"https:\/\/knjiznice.nsk.hr\/babina-greda\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/knjiznice.nsk.hr\/babina-greda\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/knjiznice.nsk.hr\/babina-greda\/wp-json\/wp\/v2\/posts?categories=14"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}