{"id":334,"count":5,"description":"","link":"http:\/\/knjiznice.nsk.hr\/ploce\/events\/kategorija\/dogadanje-za-mlade\/","name":"Doga\u0111anje za mlade","slug":"dogadanje-za-mlade","taxonomy":"tribe_events_cat","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/knjiznice.nsk.hr\/ploce\/events\/kategorija\/dogadanje-za-mlade\/\" \/>\n<meta property=\"og:locale\" content=\"hr_HR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arhiva Doga\u0111anje za mlade - Narodna knji\u017enica Plo\u010de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/knjiznice.nsk.hr\/ploce\/events\/kategorija\/dogadanje-za-mlade\/\" \/>\n<meta property=\"og:site_name\" content=\"Narodna knji\u017enica Plo\u010de\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"http:\/\/knjiznice.nsk.hr\/ploce\/#organization\",\"name\":\"Narodna knji\\u017enica Plo\\u010de\",\"url\":\"http:\/\/knjiznice.nsk.hr\/ploce\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/narodnaknjiznica.ploce\/\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/knjiznice.nsk.hr\/ploce\/#logo\",\"inLanguage\":\"hr\",\"url\":\"http:\/\/knjiznice.nsk.hr\/ploce\/wp-content\/uploads\/sites\/74\/2015\/09\/logo_1.png\",\"contentUrl\":\"http:\/\/knjiznice.nsk.hr\/ploce\/wp-content\/uploads\/sites\/74\/2015\/09\/logo_1.png\",\"width\":861,\"height\":503,\"caption\":\"Narodna knji\\u017enica Plo\\u010de\"},\"image\":{\"@id\":\"http:\/\/knjiznice.nsk.hr\/ploce\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/knjiznice.nsk.hr\/ploce\/#website\",\"url\":\"http:\/\/knjiznice.nsk.hr\/ploce\/\",\"name\":\"Narodna knji\\u017enica Plo\\u010de\",\"description\":\"\",\"publisher\":{\"@id\":\"http:\/\/knjiznice.nsk.hr\/ploce\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"http:\/\/knjiznice.nsk.hr\/ploce\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"hr\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/knjiznice.nsk.hr\/ploce\/events\/kategorija\/dogadanje-za-mlade\/#webpage\",\"url\":\"https:\/\/knjiznice.nsk.hr\/ploce\/events\/kategorija\/dogadanje-za-mlade\/\",\"name\":\"Arhiva Doga\\u0111anje za mlade - Narodna knji\\u017enica Plo\\u010de\",\"isPartOf\":{\"@id\":\"http:\/\/knjiznice.nsk.hr\/ploce\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/knjiznice.nsk.hr\/ploce\/events\/kategorija\/dogadanje-za-mlade\/#breadcrumb\"},\"inLanguage\":\"hr\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/knjiznice.nsk.hr\/ploce\/events\/kategorija\/dogadanje-za-mlade\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/knjiznice.nsk.hr\/ploce\/events\/kategorija\/dogadanje-za-mlade\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"http:\/\/knjiznice.nsk.hr\/ploce\/\",\"url\":\"http:\/\/knjiznice.nsk.hr\/ploce\/\",\"name\":\"Po\\u010detna stranica\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@id\":\"https:\/\/knjiznice.nsk.hr\/ploce\/events\/kategorija\/dogadanje-za-mlade\/#webpage\"}}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"http:\/\/knjiznice.nsk.hr\/ploce\/wp-json\/wp\/v2\/tribe_events_cat\/334"}],"collection":[{"href":"http:\/\/knjiznice.nsk.hr\/ploce\/wp-json\/wp\/v2\/tribe_events_cat"}],"about":[{"href":"http:\/\/knjiznice.nsk.hr\/ploce\/wp-json\/wp\/v2\/taxonomies\/tribe_events_cat"}]}}