{"id":42,"date":"2016-09-08T13:51:56","date_gmt":"2016-09-08T13:51:56","guid":{"rendered":"http:\/\/knjiznice.nsk.hr\/lepoglava\/?page_id=42"},"modified":"2016-09-08T13:52:13","modified_gmt":"2016-09-08T13:52:13","slug":"dokumenti","status":"publish","type":"page","link":"http:\/\/knjiznice.nsk.hr\/lepoglava\/dokumenti\/","title":{"rendered":"Pravila knji\u017enice"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":18,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/knjiznice.nsk.hr\/lepoglava\/dokumenti\/\" \/>\n<meta property=\"og:locale\" content=\"hr_HR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pravila knji\u017enice - Gradska knji\u017enica Ivana Belostenca Lepoglava\" \/>\n<meta property=\"og:url\" content=\"http:\/\/knjiznice.nsk.hr\/lepoglava\/dokumenti\/\" \/>\n<meta property=\"og:site_name\" content=\"Gradska knji\u017enica Ivana Belostenca Lepoglava\" \/>\n<meta property=\"article:modified_time\" content=\"2016-09-08T13:52:13+00:00\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/knjiznice.nsk.hr\/lepoglava\/#website\",\"url\":\"http:\/\/knjiznice.nsk.hr\/lepoglava\/\",\"name\":\"Gradska knji\\u017enica Ivana Belostenca Lepoglava\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"http:\/\/knjiznice.nsk.hr\/lepoglava\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"hr\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/knjiznice.nsk.hr\/lepoglava\/dokumenti\/#webpage\",\"url\":\"http:\/\/knjiznice.nsk.hr\/lepoglava\/dokumenti\/\",\"name\":\"Pravila knji\\u017enice - Gradska knji\\u017enica Ivana Belostenca Lepoglava\",\"isPartOf\":{\"@id\":\"http:\/\/knjiznice.nsk.hr\/lepoglava\/#website\"},\"datePublished\":\"2016-09-08T13:51:56+00:00\",\"dateModified\":\"2016-09-08T13:52:13+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/knjiznice.nsk.hr\/lepoglava\/dokumenti\/#breadcrumb\"},\"inLanguage\":\"hr\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/knjiznice.nsk.hr\/lepoglava\/dokumenti\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/knjiznice.nsk.hr\/lepoglava\/dokumenti\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"http:\/\/knjiznice.nsk.hr\/lepoglava\/\",\"url\":\"http:\/\/knjiznice.nsk.hr\/lepoglava\/\",\"name\":\"Po\\u010detna stranica\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@id\":\"http:\/\/knjiznice.nsk.hr\/lepoglava\/dokumenti\/#webpage\"}}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"http:\/\/knjiznice.nsk.hr\/lepoglava\/wp-json\/wp\/v2\/pages\/42"}],"collection":[{"href":"http:\/\/knjiznice.nsk.hr\/lepoglava\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/knjiznice.nsk.hr\/lepoglava\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/knjiznice.nsk.hr\/lepoglava\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"http:\/\/knjiznice.nsk.hr\/lepoglava\/wp-json\/wp\/v2\/comments?post=42"}],"version-history":[{"count":2,"href":"http:\/\/knjiznice.nsk.hr\/lepoglava\/wp-json\/wp\/v2\/pages\/42\/revisions"}],"predecessor-version":[{"id":44,"href":"http:\/\/knjiznice.nsk.hr\/lepoglava\/wp-json\/wp\/v2\/pages\/42\/revisions\/44"}],"wp:attachment":[{"href":"http:\/\/knjiznice.nsk.hr\/lepoglava\/wp-json\/wp\/v2\/media?parent=42"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}